{"id":3909,"date":"2023-04-02T13:02:54","date_gmt":"2023-04-02T13:02:54","guid":{"rendered":"https:\/\/rhliqeni.al\/?page_id=3909"},"modified":"2023-10-06T14:53:01","modified_gmt":"2023-10-06T14:53:01","slug":"k0-a6","status":"publish","type":"page","link":"https:\/\/rhliqeni.al\/sq\/k0-a6\/","title":{"rendered":"K0 &#8211; A6"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3909\" class=\"elementor elementor-3909\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a38c74 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9a38c74\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc7f85d\" data-id=\"cc7f85d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28ec8dd elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"28ec8dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-a0ecf1a swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"R1_Post\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-d0f1ad2 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"R2_Post\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-2f58847 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"R3_Post\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-8c95982 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"R4_Post\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b9a596 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7b9a596\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fba693a\" data-id=\"fba693a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f2409d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f2409d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-84bb8c2\" data-id=\"84bb8c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a80c5a8 elementor-widget elementor-widget-heading\" data-id=\"a80c5a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00eb dh\u00ebna<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-740148b elementor-widget elementor-widget-apartment-info\" data-id=\"740148b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"apartment-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <ul class=\"elementor-apartment-list-items\">\n                            <li class=\"elementor-apartment-list-item\" >\n                                            <span class=\"elementor-title-list\">Sip\u00ebrfaqe AP<\/span>\n                                                                    <span class=\"elementor-value-list\">87.15 m2<\/span>\n                                                        <\/li>\n                            <li class=\"elementor-apartment-list-item\" >\n                                            <span class=\"elementor-title-list elementor-title-list\">Sip\u00ebrfaqe e p\u00ebrbashk\u00ebt<\/span>\n                                                                    <span class=\"elementor-value-list\">18.45 m2<\/span>\n                                                        <\/li>\n                            <li class=\"elementor-apartment-list-item\" >\n                                            <span class=\"elementor-title-list elementor-title-list elementor-title-list\">Sip\u00ebrfaqe Totale<\/span>\n                                                                    <span class=\"elementor-value-list\">105.60<\/span>\n                                                        <\/li>\n                            <li class=\"elementor-apartment-list-item\" >\n                                            <span class=\"elementor-title-list elementor-title-list elementor-title-list elementor-title-list\">Sip\u00ebrfaqe Oborri<\/span>\n                                                                    <span class=\"elementor-value-list\">93.80 m2<\/span>\n                                                        <\/li>\n                    <\/ul>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87557cb elementor-widget elementor-widget-heading\" data-id=\"87557cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Karakteristika<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05b6c9e elementor-widget elementor-widget-apartment-info\" data-id=\"05b6c9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"apartment-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <ul class=\"elementor-apartment-list-items\">\n                            <li class=\"elementor-apartment-list-item\" >\n                                            <span class=\"elementor-title-list\">Hap\u00ebsir\u00eb ndenje<\/span>\n                                                                    <span class=\"elementor-value-list\">Kuzhin\u00eb<\/span>\n                                                        <\/li>\n                            <li class=\"elementor-apartment-list-item\" >\n                                            <span class=\"elementor-title-list elementor-title-list\">Hap\u00ebsir\u00eb ngr\u00ebnie<\/span>\n                                                                    <span class=\"elementor-value-list\">1 Tualete<\/span>\n                                                        <\/li>\n                            <li class=\"elementor-apartment-list-item\" >\n                                            <span class=\"elementor-title-list elementor-title-list elementor-title-list\">2 Dhoma gjumi<\/span>\n                                                                                <\/li>\n                    <\/ul>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-08cce31\" data-id=\"08cce31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-678cf2d elementor-heading__align-center elementor-widget elementor-widget-heading\" data-id=\"678cf2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Planimetria<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9eb11a0 elementor-heading__align-center elementor-widget elementor-widget-heading\" data-id=\"9eb11a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Apartamenti 6 \/ Kati 0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a03aef9 elementor-widget elementor-widget-image\" data-id=\"a03aef9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"685\" src=\"https:\/\/rhliqeni.al\/wp-content\/uploads\/2023\/04\/Planimetria-5.webp\" class=\"attachment-large size-large wp-image-3902\" alt=\"Ground floor two-bedroom apartment floor plan with private garden, balcony, storage room, and open-plan living space\" srcset=\"https:\/\/rhliqeni.al\/wp-content\/uploads\/2023\/04\/Planimetria-5.webp 600w, https:\/\/rhliqeni.al\/wp-content\/uploads\/2023\/04\/Planimetria-5-263x300.webp 263w, https:\/\/rhliqeni.al\/wp-content\/uploads\/2023\/04\/Planimetria-5-11x12.webp 11w, https:\/\/rhliqeni.al\/wp-content\/uploads\/2023\/04\/Planimetria-5-400x457.webp 400w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Previous slide Next slide T\u00eb dh\u00ebna Sip\u00ebrfaqe AP 87.15 m2 Sip\u00ebrfaqe e p\u00ebrbashk\u00ebt 18.45 m2 Sip\u00ebrfaqe Totale 105.60 Sip\u00ebrfaqe Oborri 93.80 m2 Karakteristika Hap\u00ebsir\u00eb ndenje Kuzhin\u00eb Hap\u00ebsir\u00eb ngr\u00ebnie 1 Tualete 2 Dhoma gjumi Planimetria Apartamenti 6 \/ Kati 0<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"content-type":"","om_disable_all_campaigns":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"iawp_total_views":2,"footnotes":""},"class_list":["post-3909","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"T\u00eb dh\u00ebna Sip\u00ebrfaqe AP 87.15 m2 Sip\u00ebrfaqe e p\u00ebrbashk\u00ebt 18.45 m2 Sip\u00ebrfaqe Totale 105.60 Sip\u00ebrfaqe Oborri 93.80 m2 Karakteristika Hap\u00ebsir\u00eb ndenje Kuzhin\u00eb Hap\u00ebsir\u00eb ngr\u00ebnie 1 Tualete 2 Dhoma gjumi Planimetria Apartamenti 6 \/ Kati 0\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/rhliqeni.al\/sq\/k0-a6\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"sq_AL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Rolling Hills - Luxury Residences\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"K0 \u2013 A6 - Rolling Hills\" \/>\n\t\t<meta property=\"og:description\" content=\"T\u00eb dh\u00ebna Sip\u00ebrfaqe AP 87.15 m2 Sip\u00ebrfaqe e p\u00ebrbashk\u00ebt 18.45 m2 Sip\u00ebrfaqe Totale 105.60 Sip\u00ebrfaqe Oborri 93.80 m2 Karakteristika Hap\u00ebsir\u00eb ndenje Kuzhin\u00eb Hap\u00ebsir\u00eb ngr\u00ebnie 1 Tualete 2 Dhoma gjumi Planimetria Apartamenti 6 \/ Kati 0\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/rhliqeni.al\/sq\/k0-a6\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/rhliqeni.al\/wp-content\/uploads\/2018\/12\/RH-Liqeni.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/rhliqeni.al\/wp-content\/uploads\/2018\/12\/RH-Liqeni.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-02T13:02:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-06T14:53:01+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rollinghillsliqeni\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"K0 \u2013 A6 - Rolling Hills\" \/>\n\t\t<meta name=\"twitter:description\" content=\"T\u00eb dh\u00ebna Sip\u00ebrfaqe AP 87.15 m2 Sip\u00ebrfaqe e p\u00ebrbashk\u00ebt 18.45 m2 Sip\u00ebrfaqe Totale 105.60 Sip\u00ebrfaqe Oborri 93.80 m2 Karakteristika Hap\u00ebsir\u00eb ndenje Kuzhin\u00eb Hap\u00ebsir\u00eb ngr\u00ebnie 1 Tualete 2 Dhoma gjumi Planimetria Apartamenti 6 \/ Kati 0\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/rhliqeni.al\/wp-content\/uploads\/2018\/12\/RH-Liqeni.png\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"K0 \u2013 A6 - Rolling Hills","description":"T\u00eb dh\u00ebna Sip\u00ebrfaqe AP 87.15 m2 Sip\u00ebrfaqe e p\u00ebrbashk\u00ebt 18.45 m2 Sip\u00ebrfaqe Totale 105.60 Sip\u00ebrfaqe Oborri 93.80 m2 Karakteristika Hap\u00ebsir\u00eb ndenje Kuzhin\u00eb Hap\u00ebsir\u00eb ngr\u00ebnie 1 Tualete 2 Dhoma gjumi Planimetria Apartamenti 6 \/ Kati 0","canonical_url":"https:\/\/rhliqeni.al\/sq\/k0-a6\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"sq_AL","og:site_name":"Rolling Hills - Luxury Residences","og:type":"article","og:title":"K0 \u2013 A6 - Rolling Hills","og:description":"T\u00eb dh\u00ebna Sip\u00ebrfaqe AP 87.15 m2 Sip\u00ebrfaqe e p\u00ebrbashk\u00ebt 18.45 m2 Sip\u00ebrfaqe Totale 105.60 Sip\u00ebrfaqe Oborri 93.80 m2 Karakteristika Hap\u00ebsir\u00eb ndenje Kuzhin\u00eb Hap\u00ebsir\u00eb ngr\u00ebnie 1 Tualete 2 Dhoma gjumi Planimetria Apartamenti 6 \/ Kati 0","og:url":"https:\/\/rhliqeni.al\/sq\/k0-a6\/","og:image":"https:\/\/rhliqeni.al\/wp-content\/uploads\/2018\/12\/RH-Liqeni.png","og:image:secure_url":"https:\/\/rhliqeni.al\/wp-content\/uploads\/2018\/12\/RH-Liqeni.png","article:published_time":"2023-04-02T13:02:54+00:00","article:modified_time":"2023-10-06T14:53:01+00:00","article:publisher":"https:\/\/www.facebook.com\/rollinghillsliqeni","twitter:card":"summary_large_image","twitter:title":"K0 \u2013 A6 - Rolling Hills","twitter:description":"T\u00eb dh\u00ebna Sip\u00ebrfaqe AP 87.15 m2 Sip\u00ebrfaqe e p\u00ebrbashk\u00ebt 18.45 m2 Sip\u00ebrfaqe Totale 105.60 Sip\u00ebrfaqe Oborri 93.80 m2 Karakteristika Hap\u00ebsir\u00eb ndenje Kuzhin\u00eb Hap\u00ebsir\u00eb ngr\u00ebnie 1 Tualete 2 Dhoma gjumi Planimetria Apartamenti 6 \/ Kati 0","twitter:image":"https:\/\/rhliqeni.al\/wp-content\/uploads\/2018\/12\/RH-Liqeni.png"},"aioseo_meta_data":{"post_id":"3909","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-04-02 13:02:55","updated":"2026-05-04 12:41:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/rhliqeni.al\/sq\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tK0 \u2013 A6\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/rhliqeni.al\/sq\/"},{"label":"K0 &#8211; A6","link":"https:\/\/rhliqeni.al\/sq\/k0-a6\/"}],"_links":{"self":[{"href":"https:\/\/rhliqeni.al\/sq\/wp-json\/wp\/v2\/pages\/3909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhliqeni.al\/sq\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rhliqeni.al\/sq\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rhliqeni.al\/sq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rhliqeni.al\/sq\/wp-json\/wp\/v2\/comments?post=3909"}],"version-history":[{"count":0,"href":"https:\/\/rhliqeni.al\/sq\/wp-json\/wp\/v2\/pages\/3909\/revisions"}],"wp:attachment":[{"href":"https:\/\/rhliqeni.al\/sq\/wp-json\/wp\/v2\/media?parent=3909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}